{"id":1544,"date":"2024-10-24T10:17:18","date_gmt":"2024-10-24T08:17:18","guid":{"rendered":"https:\/\/astratrasporti.ch\/servizio\/complete-road-and-intermodal-ftl\/"},"modified":"2024-10-24T10:17:18","modified_gmt":"2024-10-24T08:17:18","slug":"complete-road-and-intermodal-ftl","status":"publish","type":"servizio","link":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/","title":{"rendered":"Complete Road and Intermodal FTL"},"content":{"rendered":"<p>Whether national or international routes, depending on the type of goods and delivery time, we will find out the best type of vehicle to use to meet your needs (standard truck, megatrailer, refrigerated truck, truck-trailer).<br \/>For years, we have also been handling deliveries to airport warehouses with 24-hour delivery times.<\/p>\n","protected":false},"featured_media":1323,"template":"","meta":{"_acf_changed":false},"class_list":["post-1544","servizio","type-servizio","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Complete Road and Intermodal FTL - Astra Trasporti Internazionali SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Complete Road and Intermodal FTL - Astra Trasporti Internazionali SA\" \/>\n<meta property=\"og:description\" content=\"Whether national or international routes, depending on the type of goods and delivery time, we will find out the best type of vehicle to use to meet your needs (standard truck, megatrailer, refrigerated truck, truck-trailer).For years, we have also been handling deliveries to airport warehouses with 24-hour delivery times.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/\" \/>\n<meta property=\"og:site_name\" content=\"Astra Trasporti Internazionali SA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1351\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/\",\"url\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/\",\"name\":\"Complete Road and Intermodal FTL - Astra Trasporti Internazionali SA\",\"isPartOf\":{\"@id\":\"https:\/\/astratrasporti.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp\",\"datePublished\":\"2024-10-24T08:17:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#primaryimage\",\"url\":\"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp\",\"contentUrl\":\"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp\",\"width\":1351,\"height\":844},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/astratrasporti.ch\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Complete Road and Intermodal FTL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/astratrasporti.ch\/en\/#website\",\"url\":\"https:\/\/astratrasporti.ch\/en\/\",\"name\":\"Astra Trasporti Internazionali SA\",\"description\":\"Astra Trasporti Internazionali SA\",\"publisher\":{\"@id\":\"https:\/\/astratrasporti.ch\/en\/#organization\"},\"alternateName\":\"Astra Trasporti Internazionali SA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/astratrasporti.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/astratrasporti.ch\/en\/#organization\",\"name\":\"Astra Trasporti Internazionali SA\",\"alternateName\":\"Astra Trasporti Internazionali SA\",\"url\":\"https:\/\/astratrasporti.ch\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/astratrasporti.ch\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/LOGO-ASTRA-SA-scuro.webp\",\"contentUrl\":\"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/LOGO-ASTRA-SA-scuro.webp\",\"width\":1000,\"height\":514,\"caption\":\"Astra Trasporti Internazionali SA\"},\"image\":{\"@id\":\"https:\/\/astratrasporti.ch\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Complete Road and Intermodal FTL - Astra Trasporti Internazionali SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/","og_locale":"en_US","og_type":"article","og_title":"Complete Road and Intermodal FTL - Astra Trasporti Internazionali SA","og_description":"Whether national or international routes, depending on the type of goods and delivery time, we will find out the best type of vehicle to use to meet your needs (standard truck, megatrailer, refrigerated truck, truck-trailer).For years, we have also been handling deliveries to airport warehouses with 24-hour delivery times.","og_url":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/","og_site_name":"Astra Trasporti Internazionali SA","og_image":[{"width":1351,"height":844,"url":"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/","url":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/","name":"Complete Road and Intermodal FTL - Astra Trasporti Internazionali SA","isPartOf":{"@id":"https:\/\/astratrasporti.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#primaryimage"},"image":{"@id":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#primaryimage"},"thumbnailUrl":"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp","datePublished":"2024-10-24T08:17:18+00:00","breadcrumb":{"@id":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#primaryimage","url":"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp","contentUrl":"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/ie-completo-FTL.webp","width":1351,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/astratrasporti.ch\/en\/servizio\/complete-road-and-intermodal-ftl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/astratrasporti.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Complete Road and Intermodal FTL"}]},{"@type":"WebSite","@id":"https:\/\/astratrasporti.ch\/en\/#website","url":"https:\/\/astratrasporti.ch\/en\/","name":"Astra Trasporti Internazionali SA","description":"Astra Trasporti Internazionali SA","publisher":{"@id":"https:\/\/astratrasporti.ch\/en\/#organization"},"alternateName":"Astra Trasporti Internazionali SA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astratrasporti.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/astratrasporti.ch\/en\/#organization","name":"Astra Trasporti Internazionali SA","alternateName":"Astra Trasporti Internazionali SA","url":"https:\/\/astratrasporti.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/astratrasporti.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/LOGO-ASTRA-SA-scuro.webp","contentUrl":"https:\/\/astratrasporti.ch\/wp-content\/uploads\/2024\/10\/LOGO-ASTRA-SA-scuro.webp","width":1000,"height":514,"caption":"Astra Trasporti Internazionali SA"},"image":{"@id":"https:\/\/astratrasporti.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/astratrasporti.ch\/en\/wp-json\/wp\/v2\/servizio\/1544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astratrasporti.ch\/en\/wp-json\/wp\/v2\/servizio"}],"about":[{"href":"https:\/\/astratrasporti.ch\/en\/wp-json\/wp\/v2\/types\/servizio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astratrasporti.ch\/en\/wp-json\/wp\/v2\/media\/1323"}],"wp:attachment":[{"href":"https:\/\/astratrasporti.ch\/en\/wp-json\/wp\/v2\/media?parent=1544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}